{"id":4388,"date":"2023-12-01T08:36:27","date_gmt":"2023-12-01T08:36:27","guid":{"rendered":"https:\/\/littlepandas.ch\/circle-of-mothers-workshop-geneva\/"},"modified":"2024-05-18T09:09:42","modified_gmt":"2024-05-18T09:09:42","slug":"cercle-des-mamans-geneve","status":"publish","type":"page","link":"https:\/\/littlepandas.ch\/fr\/cercle-des-mamans-geneve\/","title":{"rendered":"Cercle des Mamans Gen\u00e8ve"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4388\" class=\"elementor elementor-4388 elementor-4146\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aac09d1 e-flex e-con-boxed e-con e-parent\" data-id=\"aac09d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-292ebdb elementor-widget elementor-widget-heading\" data-id=\"292ebdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chez LittlePandas, toutes les Mamans sont les bienvenues!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-423d1f0 elementor-widget elementor-widget-text-editor\" data-id=\"423d1f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre\u00a0<strong>Atelier Cercle<\/strong>\u00a0des\u00a0<strong>Mamans<\/strong>\u00a0dans notre\u00a0<strong>Kids Club<\/strong>\u00a0\u00e0\u00a0<strong>Gen\u00e8ve<\/strong>\u00a0est un lieu accueillant et respectueux o\u00f9 les\u00a0<strong>Mamans<\/strong>\u00a0se r\u00e9unissent pour discuter, partager leurs exp\u00e9riences et se soutenir mutuellement tout au long du voyage transformateur de la grossesse et de la vie postnatale. Ces mois pr\u00e9cieux repr\u00e9sentent une p\u00e9riode de changements significatifs, o\u00f9 les habitudes \u00e9voluent, o\u00f9 le b\u00e9b\u00e9 prend le devant de la sc\u00e8ne et o\u00f9 les \u00e9motions sont intenses. Faire partie d\u2019un\u00a0<strong>Cercle<\/strong>\u00a0de\u00a0<strong>Mamans<\/strong>, de soutien peut faire toute la diff\u00e9rence.<\/p><p>Chaque s\u00e9ance se concentre sur un th\u00e8me sp\u00e9cifique li\u00e9 au d\u00e9veloppement du b\u00e9b\u00e9 (comme le yoga pour b\u00e9b\u00e9s, le soulagement des inconforts par le massage et la stimulation des comp\u00e9tences motrices) ou au bien-\u00eatre maternel (comprenant la remise en forme et la gym douce). Cet atelier offre une approche holistique pour r\u00e9pondre aux besoins uniques de la m\u00e8re et du b\u00e9b\u00e9.<\/p><p>Rejoignez-nous dans notre\u00a0<strong>Kids Club\u00a0<\/strong>pour vous connecter avec des femmes courageuses \u00e0\u00a0<strong>Gen\u00e8ve<\/strong>\u00a0qui comprennent les d\u00e9fis de la maternit\u00e9. \u00c9coutez des histoires vari\u00e9es, ressentez du soutien et exprimez-vous dans un environnement bienveillant et sans jugement. Sortez de votre routine quotidienne, \u00e9chappez aux contraintes de votre domicile et participez \u00e0 des activit\u00e9s significatives avec votre b\u00e9b\u00e9.<\/p><p>En participant \u00e0 notre\u00a0<strong>Cercle<\/strong>\u00a0des\u00a0<strong>Mamans<\/strong>, vous cr\u00e9ez non seulement un lien sp\u00e9cial avec votre tout-petit, mais vous \u00e9tablirez \u00e9galement des liens avec d\u2019autres m\u00e8res qui parcourent un chemin similaire. Ensemble, nous pouvons naviguer dans les joies et les d\u00e9fis de la maternit\u00e9 avec force, empathie et un sentiment de communaut\u00e9.<\/p><p><script id=\"xverse-wallet-provider\" src=\"chrome-extension:\/\/idnnbdplmphpflfnlkomgpfbpcgelopg\/inpage.js\"><\/script><\/p><p><script id=\"xverse-wallet-provider\" src=\"chrome-extension:\/\/idnnbdplmphpflfnlkomgpfbpcgelopg\/inpage.js\"><\/script><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f7024e e-flex e-con-boxed e-con e-child\" data-id=\"3f7024e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-353dea9 elementor-widget elementor-widget-button\" data-id=\"353dea9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/littlepandas.ch\/inquiry-birthdays\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" width=\"50px\" height=\"23.917px\" viewBox=\"0 13.167 50 23.917\" xml:space=\"preserve\"><path fill=\"#FFFFFF\" d=\"M38.035,13.988c-0.406-0.008-0.777,0.234-0.941,0.605c-0.16,0.375-0.078,0.809,0.207,1.098L45.277,24H2.023 c-0.359-0.004-0.695,0.184-0.875,0.496c-0.184,0.313-0.184,0.695,0,1.008c0.18,0.313,0.516,0.5,0.875,0.496h43.254l-7.977,8.309 c-0.383,0.398-0.367,1.031,0.031,1.414s1.031,0.371,1.414-0.031L49.012,25L38.746,14.309C38.563,14.109,38.305,13.996,38.035,13.988 z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ENQUIRE NOW<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f2bfde e-flex e-con-boxed e-con e-parent\" data-id=\"0f2bfde\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b13a1d elementor-widget elementor-widget-gallery\" data-id=\"9b13a1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;justified&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;ideal_row_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:200,&quot;sizes&quot;:[]},&quot;ideal_row_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;ideal_row_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/littlepandas.ch\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-17.05.20.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9b13a1d\" data-elementor-lightbox-title=\"WhatsApp Image 2023-11-29 at 17.05.20\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA1MCwidXJsIjoiaHR0cHM6XC9cL2xpdHRsZXBhbmRhcy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMTFcL1doYXRzQXBwLUltYWdlLTIwMjMtMTEtMjktYXQtMTcuMDUuMjAuanBlZyIsInNsaWRlc2hvdyI6IjliMTNhMWQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/littlepandas.ch\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-17.05.20-225x300.jpeg\" data-width=\"225\" data-height=\"300\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/littlepandas.ch\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-17.07.38.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9b13a1d\" data-elementor-lightbox-title=\"WhatsApp Image 2023-11-29 at 17.07.38\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA1NCwidXJsIjoiaHR0cHM6XC9cL2xpdHRsZXBhbmRhcy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMTFcL1doYXRzQXBwLUltYWdlLTIwMjMtMTEtMjktYXQtMTcuMDcuMzguanBlZyIsInNsaWRlc2hvdyI6IjliMTNhMWQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/littlepandas.ch\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-17.07.38-169x300.jpeg\" data-width=\"169\" data-height=\"300\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/littlepandas.ch\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-17.07.39.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9b13a1d\" data-elementor-lightbox-title=\"WhatsApp Image 2023-11-29 at 17.07.39\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA1NiwidXJsIjoiaHR0cHM6XC9cL2xpdHRsZXBhbmRhcy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMTFcL1doYXRzQXBwLUltYWdlLTIwMjMtMTEtMjktYXQtMTcuMDcuMzkuanBlZyIsInNsaWRlc2hvdyI6IjliMTNhMWQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/littlepandas.ch\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-17.07.39-169x300.jpeg\" data-width=\"169\" data-height=\"300\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/littlepandas.ch\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-17.07.37.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9b13a1d\" data-elementor-lightbox-title=\"WhatsApp Image 2023-11-29 at 17.07.37\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA1MiwidXJsIjoiaHR0cHM6XC9cL2xpdHRsZXBhbmRhcy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMTFcL1doYXRzQXBwLUltYWdlLTIwMjMtMTEtMjktYXQtMTcuMDcuMzcuanBlZyIsInNsaWRlc2hvdyI6IjliMTNhMWQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/littlepandas.ch\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-29-at-17.07.37-225x300.jpeg\" data-width=\"225\" data-height=\"300\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/littlepandas.ch\/wp-content\/uploads\/2023\/11\/Barbie-Theme-Birthday-Party-2.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9b13a1d\" data-elementor-lightbox-title=\"Barbie Theme Birthday Party (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA0NSwidXJsIjoiaHR0cHM6XC9cL2xpdHRsZXBhbmRhcy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMTFcL0JhcmJpZS1UaGVtZS1CaXJ0aGRheS1QYXJ0eS0yLmpwZWciLCJzbGlkZXNob3ciOiI5YjEzYTFkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/littlepandas.ch\/wp-content\/uploads\/2023\/11\/Barbie-Theme-Birthday-Party-2-169x300.jpeg\" data-width=\"169\" data-height=\"300\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/littlepandas.ch\/wp-content\/uploads\/2023\/11\/Barbie-Theme-Birthday-Party-1.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9b13a1d\" data-elementor-lightbox-title=\"Barbie Theme Birthday Party (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA0OCwidXJsIjoiaHR0cHM6XC9cL2xpdHRsZXBhbmRhcy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMTFcL0JhcmJpZS1UaGVtZS1CaXJ0aGRheS1QYXJ0eS0xLmpwZWciLCJzbGlkZXNob3ciOiI5YjEzYTFkIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/littlepandas.ch\/wp-content\/uploads\/2023\/11\/Barbie-Theme-Birthday-Party-1-169x300.jpeg\" data-width=\"169\" data-height=\"300\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-973091a elementor-widget elementor-widget-spacer\" data-id=\"973091a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53e5770 e-flex e-con-boxed e-con e-parent\" data-id=\"53e5770\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e7d03e4 elementor-widget elementor-widget-heading\" data-id=\"e7d03e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Foire Aux Questions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1aeefaf e-flex e-con-boxed e-con e-child\" data-id=\"1aeefaf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d85916 elementor-widget elementor-widget-toggle\" data-id=\"2d85916\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4771\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-4771\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Qu'est-ce que l\u2019atelier Cercle des Mamans?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-4771\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-4771\"><p><span style=\"font-weight: 400;\">Le <\/span><b>Cercle des Mamans<\/b><span style=\"font-weight: 400;\"> est un rassemblement bienveillant et nourrissant con\u00e7u pour permettre aux m\u00e8res de se retrouver dans un espace s\u00e9curis\u00e9 pour partager des exp\u00e9riences, se soutenir mutuellement et apprendre des parcours de chacune \u00e0 travers la maternit\u00e9.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4772\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-4772\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quels sujets sont abord\u00e9s dans l\u2019atelier Cercle des Mamans?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-4772\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-4772\"><p><span style=\"font-weight: 400;\">L\u2019atelier <\/span><b>Cercle des Mamans<\/b><span style=\"font-weight: 400;\"> couvre un large \u00e9ventail de sujets li\u00e9s \u00e0 la maternit\u00e9, comprenant notamment mais sans s&rsquo;y limiter: les d\u00e9fis de la parentalit\u00e9, les soins personnels, la gestion du stress, le renforcement de la r\u00e9silience, la promotion de relations saines et la recherche d&rsquo;\u00e9quilibre dans la vie quotidienne.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4773\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-4773\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Qui peut assister \u00e0 l\u2019atelier Cercle des Mamans?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-4773\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-4773\"><p><span style=\"font-weight: 400;\">L\u2019atelier <\/span><b>Cercle des Mamans<\/b><span style=\"font-weight: 400;\"> est ouvert \u00e0 toutes les m\u00e8res, quel que soit leur parcours, leur \u00e2ge ou leur exp\u00e9rience en tant que parent. Que vous soyez une jeune maman, une maman exp\u00e9riment\u00e9e ou une future maman, vous \u00eates les bienvenues dans notre cercle.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4774\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-4774\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment sont structur\u00e9es l\u2019atelier Cercle des Mamans?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-4774\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-4774\"><p><span style=\"font-weight: 400;\">Cet atelier est structur\u00e9 sous forme de discussions de groupe facilit\u00e9es par un animateur form\u00e9 ou une m\u00e8re exp\u00e9riment\u00e9e. Chaque session commence g\u00e9n\u00e9ralement par un point de contr\u00f4le o\u00f9 les m\u00e8res ont l&rsquo;opportunit\u00e9 de partager leurs pens\u00e9es, leurs pr\u00e9occupations ou leurs succ\u00e8s, suivies de discussions guid\u00e9es sur des sujets ou th\u00e8mes sp\u00e9cifiques.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4775\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-4775\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quels sont les avantages de rejoindre l\u2019atelier Cercle des Mamans?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-4775\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-4775\"><p><span style=\"font-weight: 400;\">L\u2019atelier <\/span><b>Cercle des Mamans<\/b><span style=\"font-weight: 400;\"> offre une communaut\u00e9 de soutien o\u00f9 les m\u00e8res peuvent se connecter avec d&rsquo;autres partageant des exp\u00e9riences et des d\u00e9fis similaires. Elle offre un espace de soutien \u00e9motionnel, de validation et d&rsquo;encouragement, aidant les m\u00e8res \u00e0 se sentir moins isol\u00e9es et plus autonomes dans leur parcours de maternit\u00e9.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Qu'est-ce que l\\u2019atelier Cercle des Mamans?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Le <\\\/span><b>Cercle des Mamans<\\\/b><span style=\\\"font-weight: 400;\\\"> est un rassemblement bienveillant et nourrissant con\\u00e7u pour permettre aux m\\u00e8res de se retrouver dans un espace s\\u00e9curis\\u00e9 pour partager des exp\\u00e9riences, se soutenir mutuellement et apprendre des parcours de chacune \\u00e0 travers la maternit\\u00e9.<\\\/span><\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Quels sujets sont abord\\u00e9s dans l\\u2019atelier Cercle des Mamans?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">L\\u2019atelier <\\\/span><b>Cercle des Mamans<\\\/b><span style=\\\"font-weight: 400;\\\"> couvre un large \\u00e9ventail de sujets li\\u00e9s \\u00e0 la maternit\\u00e9, comprenant notamment mais sans s&rsquo;y limiter: les d\\u00e9fis de la parentalit\\u00e9, les soins personnels, la gestion du stress, le renforcement de la r\\u00e9silience, la promotion de relations saines et la recherche d&rsquo;\\u00e9quilibre dans la vie quotidienne.<\\\/span><\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Qui peut assister \\u00e0 l\\u2019atelier Cercle des Mamans?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">L\\u2019atelier <\\\/span><b>Cercle des Mamans<\\\/b><span style=\\\"font-weight: 400;\\\"> est ouvert \\u00e0 toutes les m\\u00e8res, quel que soit leur parcours, leur \\u00e2ge ou leur exp\\u00e9rience en tant que parent. Que vous soyez une jeune maman, une maman exp\\u00e9riment\\u00e9e ou une future maman, vous \\u00eates les bienvenues dans notre cercle.<\\\/span><\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Comment sont structur\\u00e9es l\\u2019atelier Cercle des Mamans?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Cet atelier est structur\\u00e9 sous forme de discussions de groupe facilit\\u00e9es par un animateur form\\u00e9 ou une m\\u00e8re exp\\u00e9riment\\u00e9e. Chaque session commence g\\u00e9n\\u00e9ralement par un point de contr\\u00f4le o\\u00f9 les m\\u00e8res ont l&rsquo;opportunit\\u00e9 de partager leurs pens\\u00e9es, leurs pr\\u00e9occupations ou leurs succ\\u00e8s, suivies de discussions guid\\u00e9es sur des sujets ou th\\u00e8mes sp\\u00e9cifiques.<\\\/span><\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Quels sont les avantages de rejoindre l\\u2019atelier Cercle des Mamans?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">L\\u2019atelier <\\\/span><b>Cercle des Mamans<\\\/b><span style=\\\"font-weight: 400;\\\"> offre une communaut\\u00e9 de soutien o\\u00f9 les m\\u00e8res peuvent se connecter avec d&rsquo;autres partageant des exp\\u00e9riences et des d\\u00e9fis similaires. Elle offre un espace de soutien \\u00e9motionnel, de validation et d&rsquo;encouragement, aidant les m\\u00e8res \\u00e0 se sentir moins isol\\u00e9es et plus autonomes dans leur parcours de maternit\\u00e9.<\\\/span><\\\/p>\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2872f1c e-flex e-con-boxed e-con e-parent\" data-id=\"2872f1c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45c95d1 elementor-widget elementor-widget-image\" data-id=\"45c95d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/littlepandas.ch\/wp-content\/uploads\/2023\/07\/hollie-santos-aUtvHsu8Uzk-unsplash-scaled.jpg\" class=\"attachment-large size-large wp-image-3039\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Chez LittlePandas, toutes les Mamans sont les bienvenues! Notre\u00a0Atelier Cercle\u00a0des\u00a0Mamans\u00a0dans notre\u00a0Kids Club\u00a0\u00e0\u00a0Gen\u00e8ve\u00a0est un lieu accueillant et respectueux o\u00f9 les\u00a0Mamans\u00a0se r\u00e9unissent pour discuter, partager leurs exp\u00e9riences et se soutenir mutuellement tout au long du voyage transformateur de la grossesse et de la vie postnatale. Ces mois pr\u00e9cieux repr\u00e9sentent une p\u00e9riode de changements significatifs, o\u00f9 les habitudes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3039,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Cercle des Mamans Gen\u00e8ve | Maman Gen\u00e8ve","_seopress_titles_desc":"Notre Atelier Cercle des Mamans dans notre Kids Club \u00e0 Gen\u00e8ve est un lieu accueillant et respectueux o\u00f9 les Mamans se r\u00e9unissent pour discuter, partager leurs exp\u00e9riences et se soutenir mutuellement tout au long du voyage transformateur de la grossesse et de la vie postnatale. Ces mois pr\u00e9cieux repr\u00e9sentent une p\u00e9riode de changements significatifs, o\u00f9 les habitudes \u00e9voluent, o\u00f9 le b\u00e9b\u00e9 prend le devant de la sc\u00e8ne et o\u00f9 les \u00e9motions sont intenses. Faire partie d\u2019un Cercle de Mamans, de soutien peut faire toute la diff\u00e9rence.\r\n\r\nChaque s\u00e9ance se concentre sur un th\u00e8me sp\u00e9cifique li\u00e9 au d\u00e9veloppement du b\u00e9b\u00e9 (comme le yoga pour b\u00e9b\u00e9s, le soulagement des inconforts par le massage et la stimulation des comp\u00e9tences motrices) ou au bien-\u00eatre maternel (comprenant la remise en forme et la gym douce). Cet atelier offre une approche holistique pour r\u00e9pondre aux besoins uniques de la m\u00e8re et du b\u00e9b\u00e9.\r\n\r\nRejoignez-nous dans notre Kids Club pour vous connecter avec des femmes courageuses \u00e0 Gen\u00e8ve qui comprennent les d\u00e9fis de la maternit\u00e9. \u00c9coutez des histoires vari\u00e9es, ressentez du soutien et exprimez-vous dans un environnement bienveillant et sans jugement. Sortez de votre routine quotidienne, \u00e9chappez aux contraintes de votre domicile et participez \u00e0 des activit\u00e9s significatives avec votre b\u00e9b\u00e9.\r\n\r\nEn participant \u00e0 notre Cercle des Mamans, vous cr\u00e9ez non seulement un lien sp\u00e9cial avec votre tout-petit, mais vous \u00e9tablirez \u00e9galement des liens avec d\u2019autres m\u00e8res qui parcourent un chemin similaire. Ensemble, nous pouvons naviguer dans les joies et les d\u00e9fis de la maternit\u00e9 avec force, empathie et un sentiment de communaut\u00e9.","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-4388","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/littlepandas.ch\/fr\/wp-json\/wp\/v2\/pages\/4388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/littlepandas.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/littlepandas.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/littlepandas.ch\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/littlepandas.ch\/fr\/wp-json\/wp\/v2\/comments?post=4388"}],"version-history":[{"count":0,"href":"https:\/\/littlepandas.ch\/fr\/wp-json\/wp\/v2\/pages\/4388\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/littlepandas.ch\/fr\/wp-json\/wp\/v2\/media\/3039"}],"wp:attachment":[{"href":"https:\/\/littlepandas.ch\/fr\/wp-json\/wp\/v2\/media?parent=4388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}